{"id":15195,"date":"2018-03-13T07:37:58","date_gmt":"2018-03-13T07:37:58","guid":{"rendered":"https:\/\/blog.windsorbrokers.com\/?p=15195"},"modified":"2018-03-13T07:37:58","modified_gmt":"2018-03-13T07:37:58","slug":"%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa","status":"publish","type":"post","link":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/","title":{"rendered":"\u064a\u0648\u0631\u0648 \u0645\u0642\u0627\u0628\u0644 \u0627\u0644\u062f\u0648\u0644\u0627\u0631 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0648\u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0628\u0639\u062f \u062a\u0635\u0631\u064a\u062d\u0627\u062a \u0645\u0633\u0626\u0648\u0644\u064a \u0623\u0648\u0631\u0648\u0628\u0627"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15196\" src=\"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/03\/EURUSDH1-2.png\" alt=\"\" width=\"1596\" height=\"716\" srcset=\"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/03\/EURUSDH1-2.png 1596w, https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/03\/EURUSDH1-2-300x135.png 300w, https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/03\/EURUSDH1-2-768x345.png 768w, https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/03\/EURUSDH1-2-1024x459.png 1024w\" sizes=\"auto, (max-width: 1596px) 100vw, 1596px\" \/><\/p>\n<p style=\"text-align: right;\">\u062a\u062f\u0627\u0648\u0644 \u0632\u0648\u062c \u0627\u0644\u064a\u0648\u0631\u0648 \u062f\u0648\u0644\u0627\u0631 \u00a0\u0641\u064a \u062d\u062f\u0648\u062f 60 \u0646\u0642\u0637\u0629 \u00a0\u0645\u0639 \u0625\u062a\u062c\u0627\u0647 \u0639\u0627\u0645 \u0645\u062d\u0627\u064a\u062f \u062d\u064a\u062b \u0625\u0641\u062a\u062a\u062d \u0639\u0646\u062f 1.2310 \u0648\u00a0 \u0623\u063a\u0644\u0642 \u0639\u0646\u062f 1.2334 \u0648 \u00a0\u0648\u0635\u0644 \u00a0\u0644\u0623\u0639\u0644\u064a \u0633\u0639\u0631 \u0639\u0646\u062f 1.2345 \u0623\u062f\u0646\u064a \u0633\u0639\u0631 \u0644\u0644\u0632\u0648\u062c \u0639\u0646\u062f 1.2290 \u00a0\u0648 \u0646\u062c\u062d \u0627\u0644\u0632\u0648\u062c \u0641\u064a \u062a\u062d\u0642\u064a\u0642 \u0645\u0633\u062a\u0647\u062f\u0641\u0647 \u0627\u0644\u0623\u0648\u0644 \u0639\u0646\u062f\u00a0 1.2320<\/p>\n<p style=\"text-align: right;\">\u0648 \u062a\u062f\u0627\u0648\u0644 \u0627\u0644\u0632\u0648\u062c \u0627\u0644\u064a\u0648\u0645 \u0628\u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0627\u0639\u0644\u0649 \u0646\u0642\u0637\u062a\u0629 \u0627\u0644\u0645\u062d\u0648\u0631\u064a\u0629 1.2320 , \u0648 \u0627\u0639\u0644\u0649 \u0627\u0644\u0645\u062a\u0648\u0633\u0637\u0627\u062a \u0627\u0644\u0633\u0639\u0631\u064a\u0629 20\u00a0 55 , \u0648 \u0645\u0646 \u062a\u062f\u0627\u0648\u0644\u0647 \u0627\u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u064a 50 \u0641\u064a\u0628\u0648\u0646\u0627\u062a\u0634\u064a ( \u0644\u0644\u0645\u0648\u062c\u0629 \u0627\u0644\u0647\u0627\u0628\u0637\u0629 \u0645\u0646 1.4000 \u0628\u062a\u0627\u0631\u064a\u062e 25 \u0645\u0627\u064a\u0648 \u00a02015 )\u00a0 , \u0648 \u0645\u0646 \u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0631 \u0639\u0644\u064a \u0645\u0624\u0634\u0631 \u0627\u0644\u0633\u062a\u0648\u0643\u0627\u0633\u062a\u0643 \u0628\u062a\u0642\u0627\u0637\u0639 \u062e\u0637\u0648\u0637\u0647 \u0644\u0627\u0639\u0644\u0649, \u0648 \u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0627\u0644\u0632\u0648\u062c \u0639\u0644\u0649 \u0645\u0624\u0634\u0631 \u0627\u0644\u0633\u0627\u0631 \u0648 \u0627\u064a\u062c\u0627\u0628\u064a\u0629 \u0627\u0644\u0632\u0648\u062c \u0639\u0644\u064a \u0645\u0624\u0634\u0631 \u0627\u0644\u0625\u064a \u0625\u0645 \u0623\u064a\u0647 , \u0648 \u0625\u064a\u062c\u0627\u0628\u064a\u062a\u0647 \u0639\u0644\u064a \u0645\u0624\u0634\u0631 \u0627\u0644\u0641\u0644\u0627\u062a \u062a\u0631\u0646\u062f \u00a0\u062a\u062c\u0639\u0644\u0646\u0627 \u0646\u0631\u062c\u062d \u0627\u0644\u0625\u062a\u062c\u0627\u0647 \u0627\u0644\u0645\u062d\u0627\u064a\u062f \u0627\u0644\u064a\u0648\u0645<\/p>\n<p style=\"text-align: right;\"><strong>\u0627\u0644\u0633\u064a\u0646\u0627\u0631\u064a\u0648 \u0627\u0644\u0645\u062a\u0648\u0642\u0639\u00a0<\/strong><\/p>\n<p style=\"text-align: right;\">\u0643\u0633\u0631 1.2360 \u0635\u0639\u0648\u062f\u0627 \u0627\u0644\u0649 1.2400 \u062b\u0645 1.2430<\/p>\n<p style=\"text-align: right;\"><strong>\u0627\u0644\u0633\u064a\u0646\u0627\u0631\u064a\u0648 \u0627\u0644\u0645\u0639\u0627\u0643\u0633\u00a0<\/strong><\/p>\n<p style=\"text-align: right;\">\u0643\u0633\u0631 1.2290 \u0647\u0628\u0648\u0637\u0627 \u0627\u0644\u0649 1.2260 \u062b\u0645 1.2225<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u062f\u0627\u0648\u0644 \u0632\u0648\u062c \u0627\u0644\u064a\u0648\u0631\u0648 \u062f\u0648\u0644\u0627\u0631 \u00a0\u0641\u064a \u062d\u062f\u0648\u062f 60 \u0646\u0642\u0637\u0629 \u00a0\u0645\u0639 \u0625\u062a\u062c\u0627\u0647 \u0639\u0627\u0645 \u0645\u062d\u0627\u064a\u062f \u062d\u064a\u062b \u0625\u0641\u062a\u062a\u062d \u0639\u0646\u062f 1.2310 \u0648\u00a0 \u0623\u063a\u0644\u0642 \u0639\u0646\u062f 1.2334 \u0648 \u00a0\u0648\u0635\u0644 \u00a0\u0644\u0623\u0639\u0644\u064a \u0633\u0639\u0631 \u0639\u0646\u062f 1.2345 \u0623\u062f\u0646\u064a \u0633\u0639\u0631 \u0644\u0644\u0632\u0648\u062c \u0639\u0646\u062f 1.2290 \u00a0\u0648 \u0646\u062c\u062d \u0627\u0644\u0632\u0648\u062c \u0641\u064a \u062a\u062d\u0642\u064a\u0642 \u0645\u0633\u062a\u0647\u062f\u0641\u0647 \u0627\u0644\u0623\u0648\u0644 \u0639\u0646\u062f\u00a0 1.2320 \u0648 \u062a\u062f\u0627\u0648\u0644 \u0627\u0644\u0632\u0648\u062c \u0627\u0644\u064a\u0648\u0645 \u0628\u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0627\u0639\u0644\u0649 \u0646\u0642\u0637\u062a\u0629 \u0627\u0644\u0645\u062d\u0648\u0631\u064a\u0629 1.2320 , \u0648 \u0627\u0639\u0644\u0649 \u0627\u0644\u0645\u062a\u0648\u0633\u0637\u0627\u062a \u0627\u0644\u0633\u0639\u0631\u064a\u0629 20\u00a0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13776,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274],"tags":[276,297],"class_list":["post-15195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-274","tag-276","tag-297"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Windsor Brokers Blog | Forex Market Analysis &amp; Trading Insights<\/title>\n<meta name=\"description\" content=\"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windsor Brokers Blog | Forex Market Analysis &amp; Trading Insights\" \/>\n<meta property=\"og:description\" content=\"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/\" \/>\n<meta property=\"og:site_name\" content=\"Windsor Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/windsorbrokers\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-13T07:37:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/EURUSD.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Karim Magdy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@windsorbrokers\" \/>\n<meta name=\"twitter:site\" content=\"@windsorbrokers\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"Karim Magdy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/\"},\"author\":{\"name\":\"Karim Magdy\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/person\\\/7e247c3c8eb38165d695d129be270921\"},\"headline\":\"\u064a\u0648\u0631\u0648 \u0645\u0642\u0627\u0628\u0644 \u0627\u0644\u062f\u0648\u0644\u0627\u0631 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0648\u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0628\u0639\u062f \u062a\u0635\u0631\u064a\u062d\u0627\u062a \u0645\u0633\u0626\u0648\u0644\u064a \u0623\u0648\u0631\u0648\u0628\u0627\",\"datePublished\":\"2018-03-13T07:37:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/EURUSD.png\",\"keywords\":[\"\u0641\u0648\u0631\u0643\u0633\",\"\u0648\u0646\u062f\u0633\u0648\u0631_\u0628\u0631\u0648\u0643\u0631\u0632\"],\"articleSection\":[\"\u0627\u0644\u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u064a\u0648\u0645\u064a\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/\",\"name\":\"Windsor Brokers Blog | Forex Market Analysis & Trading Insights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/EURUSD.png\",\"datePublished\":\"2018-03-13T07:37:58+00:00\",\"description\":\"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/EURUSD.png\",\"contentUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/EURUSD.png\",\"width\":600,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u064a\u0648\u0631\u0648 \u0645\u0642\u0627\u0628\u0644 \u0627\u0644\u062f\u0648\u0644\u0627\u0631 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0648\u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0628\u0639\u062f \u062a\u0635\u0631\u064a\u062d\u0627\u062a \u0645\u0633\u0626\u0648\u0644\u064a \u0623\u0648\u0631\u0648\u0628\u0627\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/\",\"name\":\"Windsor Brokers Blog\",\"description\":\"Forex &amp; CFD Market Analysis\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#organization\",\"name\":\"Windsor Brokers\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Windsor-Brokers.png\",\"contentUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Windsor-Brokers.png\",\"width\":600,\"height\":350,\"caption\":\"Windsor Brokers\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/windsorbrokers\",\"https:\\\/\\\/x.com\\\/windsorbrokers\",\"https:\\\/\\\/www.instagram.com\\\/windsorbrokerscom\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/windsorbrokersforex\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/windsor-brokers\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/person\\\/7e247c3c8eb38165d695d129be270921\",\"name\":\"Karim Magdy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37b06e6919c6f2425fae961a7996c63a3c5db711cca832e3cfb7d2a708595bbc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37b06e6919c6f2425fae961a7996c63a3c5db711cca832e3cfb7d2a708595bbc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/37b06e6919c6f2425fae961a7996c63a3c5db711cca832e3cfb7d2a708595bbc?s=96&d=mm&r=g\",\"caption\":\"Karim Magdy\"},\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/author\\\/karim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Windsor Brokers Blog | Forex Market Analysis & Trading Insights","description":"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"ar_AR","og_type":"article","og_title":"Windsor Brokers Blog | Forex Market Analysis & Trading Insights","og_description":"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.","og_url":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/","og_site_name":"Windsor Blog","article_publisher":"https:\/\/www.facebook.com\/windsorbrokers","article_published_time":"2018-03-13T07:37:58+00:00","og_image":[{"width":600,"height":312,"url":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/EURUSD.png","type":"image\/png"}],"author":"Karim Magdy","twitter_card":"summary_large_image","twitter_creator":"@windsorbrokers","twitter_site":"@windsorbrokers","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"Karim Magdy"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/#article","isPartOf":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/"},"author":{"name":"Karim Magdy","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/person\/7e247c3c8eb38165d695d129be270921"},"headline":"\u064a\u0648\u0631\u0648 \u0645\u0642\u0627\u0628\u0644 \u0627\u0644\u062f\u0648\u0644\u0627\u0631 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0648\u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0628\u0639\u062f \u062a\u0635\u0631\u064a\u062d\u0627\u062a \u0645\u0633\u0626\u0648\u0644\u064a \u0623\u0648\u0631\u0648\u0628\u0627","datePublished":"2018-03-13T07:37:58+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/"},"wordCount":0,"publisher":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#organization"},"image":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/EURUSD.png","keywords":["\u0641\u0648\u0631\u0643\u0633","\u0648\u0646\u062f\u0633\u0648\u0631_\u0628\u0631\u0648\u0643\u0631\u0632"],"articleSection":["\u0627\u0644\u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u064a\u0648\u0645\u064a"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/","url":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/","name":"Windsor Brokers Blog | Forex Market Analysis & Trading Insights","isPartOf":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/#primaryimage"},"image":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/EURUSD.png","datePublished":"2018-03-13T07:37:58+00:00","description":"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.","breadcrumb":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/#primaryimage","url":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/EURUSD.png","contentUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/EURUSD.png","width":600,"height":312},{"@type":"BreadcrumbList","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d9%8a%d9%88%d8%b1%d9%88-%d9%85%d9%82%d8%a7%d8%a8%d9%84-%d8%a7%d9%84%d8%af%d9%88%d9%84%d8%a7%d8%b1-%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d9%8a%d9%83%d9%8a-%d9%88%d9%85%d8%ad%d8%a7%d9%88%d9%84%d8%a7%d8%aa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.windsorbrokers.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u064a\u0648\u0631\u0648 \u0645\u0642\u0627\u0628\u0644 \u0627\u0644\u062f\u0648\u0644\u0627\u0631 \u0627\u0644\u0623\u0645\u0631\u064a\u0643\u064a \u0648\u0645\u062d\u0627\u0648\u0644\u0627\u062a \u0625\u064a\u062c\u0627\u0628\u064a\u0629 \u0628\u0639\u062f \u062a\u0635\u0631\u064a\u062d\u0627\u062a \u0645\u0633\u0626\u0648\u0644\u064a \u0623\u0648\u0631\u0648\u0628\u0627"}]},{"@type":"WebSite","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#website","url":"https:\/\/blog.windsorbrokers.com\/ar\/","name":"Windsor Brokers Blog","description":"Forex &amp; CFD Market Analysis","publisher":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.windsorbrokers.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#organization","name":"Windsor Brokers","url":"https:\/\/blog.windsorbrokers.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2023\/05\/Windsor-Brokers.png","contentUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2023\/05\/Windsor-Brokers.png","width":600,"height":350,"caption":"Windsor Brokers"},"image":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/windsorbrokers","https:\/\/x.com\/windsorbrokers","https:\/\/www.instagram.com\/windsorbrokerscom\/","https:\/\/www.youtube.com\/user\/windsorbrokersforex","https:\/\/www.linkedin.com\/company\/windsor-brokers\/"]},{"@type":"Person","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/person\/7e247c3c8eb38165d695d129be270921","name":"Karim Magdy","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/37b06e6919c6f2425fae961a7996c63a3c5db711cca832e3cfb7d2a708595bbc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/37b06e6919c6f2425fae961a7996c63a3c5db711cca832e3cfb7d2a708595bbc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/37b06e6919c6f2425fae961a7996c63a3c5db711cca832e3cfb7d2a708595bbc?s=96&d=mm&r=g","caption":"Karim Magdy"},"url":"https:\/\/blog.windsorbrokers.com\/ar\/author\/karim\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts\/15195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/comments?post=15195"}],"version-history":[{"count":1,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts\/15195\/revisions"}],"predecessor-version":[{"id":15197,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts\/15195\/revisions\/15197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/media\/13776"}],"wp:attachment":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/media?parent=15195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/categories?post=15195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/tags?post=15195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}