{"id":16088,"date":"2018-04-06T06:57:29","date_gmt":"2018-04-06T06:57:29","guid":{"rendered":"https:\/\/blog.windsorbrokers.com\/?p=16088"},"modified":"2018-04-06T06:57:29","modified_gmt":"2018-04-06T06:57:29","slug":"%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84","status":"publish","type":"post","link":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/","title":{"rendered":"\u0627\u0644\u0630\u0647\u0628 \u064a\u062a\u0639\u0631\u0636 \u0644\u0645\u0648\u062c\u0629 \u0628\u064a\u0639 \u0642\u0648\u064a\u0629 \u0648\u0633\u0637 \u062a\u0631\u0627\u062c\u0639 \u0627\u0644\u0637\u0644\u0628 \u0639\u0644\u0649 \u0627\u0644\u0645\u0644\u0627\u0630\u0627\u062a \u0627\u0644\u0627\u0645\u0646\u0629 \u0628\u0639\u062f \u0627\u0646\u062d\u0633\u0627\u0631 \u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629"},"content":{"rendered":"<p style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16089\" src=\"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/04\/XAUUSDH1-3.png\" alt=\"\" width=\"1436\" height=\"590\" srcset=\"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/04\/XAUUSDH1-3.png 1436w, https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/04\/XAUUSDH1-3-300x123.png 300w, https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/04\/XAUUSDH1-3-768x316.png 768w, https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/04\/XAUUSDH1-3-1024x421.png 1024w\" sizes=\"auto, (max-width: 1436px) 100vw, 1436px\" \/>\u062a\u062f\u0627\u0648\u0644 \u0645\u0639\u062f\u0646 \u0627\u0644\u0630\u0647\u0628 \u0641\u064a \u062d\u062f\u0648\u062f 90 \u0646\u0642\u0637\u0629 \u0645\u0639 \u0625\u062a\u062c\u0627\u0647 \u0639\u0627\u0645 \u0647\u0627\u0628\u0637 \u062d\u064a\u062b \u0625\u0641\u062a\u062a\u062d \u0639\u0646\u062f 1326.27 \u0648 \u0623\u063a\u0644\u0642 \u0639\u0646\u062f 1326.23 \u0648 \u0648\u0635\u0644 \u0644\u0623\u0639\u0644\u064a \u0633\u0639\u0631 \u0639\u0646\u062f 1333.32 \u0643\u0627\u0646 \u0623\u062f\u0646\u064a \u0633\u0639\u0631 \u0644\u0644\u0630\u0647\u0628 \u0639\u0646\u062f 1325.44 \u0646\u062c\u062d \u0627\u0644\u0645\u0639\u062f\u0646 \u0641\u064a \u062a\u062d\u0642\u064a\u0642 \u0645\u0633\u062a\u0647\u062f\u0641\u0647 \u0627\u0644\u0623\u0648\u0644 \u0639\u0646\u062f 1332 .<br \/>\n\u0648 \u062a\u062f\u0627\u0648\u0644 \u0627\u0644\u0645\u0639\u062f\u0646 \u0627\u0644\u064a\u0648\u0645 \u0628\u0633\u0644\u0628\u064a\u0629 \u0627\u0633\u0641\u0644 \u0646\u0642\u0637\u062a\u0629 \u0627\u0644\u0645\u062d\u0648\u0631\u064a\u0629 1332, \u0648\u062a\u062f\u0627\u0648\u0644 \u0627\u0644\u0632\u0648\u062c \u0627\u0633\u0641\u0644 \u0627\u0644\u0645\u062a\u0648\u0633\u0637\u0627\u062a \u0627\u0644\u0633\u0639\u0631\u064a\u0629 20 55 , \u0648\u0639\u0644\u0649 \u0627\u0644\u0631\u063a\u0645 \u0645\u0646 \u062a\u062f\u0627\u0648\u0644\u0647 \u0627\u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u064a 38.2 \u0641\u064a\u0628\u0648\u0646\u0627\u062a\u0634\u064a ( \u0644\u0644\u0645\u0648\u062c\u0629 \u0627\u0644\u0647\u0627\u0628\u0637\u0629 1790\u0628\u062a\u0627\u0631\u064a\u062e \u0623\u0643\u062a\u0648\u0628\u0631 2012 ) , \u0648 \u0644\u0643\u0646 \u0633\u0644\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0631 \u0639\u0644\u064a \u0645\u0624\u0634\u0631 \u0627\u0644\u0633\u062a\u0648\u0643\u0627\u0633\u062a\u0643 \u0628\u062a\u0642\u0627\u0637\u0639 \u062e\u0637\u0648\u0637\u0647 \u0644\u0627\u0633\u0641\u0644,\u0648 \u0645\u0646 \u0633\u0644\u0628\u064a\u0629 \u0627\u0644\u0645\u0639\u062f\u0646 \u0639\u0644\u0649 \u0645\u0624\u0634\u0631 \u0627\u0644\u0633\u0627\u0631 \u0648 \u0633\u0644\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0631 \u0639\u0644\u064a \u0645\u0624\u0634\u0631 \u0627\u0644\u0625\u064a \u0625\u0645 \u0623\u064a\u0647 , \u0648 \u0633\u0644\u0628\u064a\u0629 \u0639\u0644\u064a \u0645\u0624\u0634\u0631 \u0627\u0644\u0641\u0644\u0627\u062a \u062a\u0631\u0646\u062f \u0648 \u0644\u0630\u0644\u0643 \u0646\u0631\u062c\u062d \u0627\u0644\u0627\u062a\u062c\u0627\u0647 \u0627\u0644\u0647\u0627\u0628\u0637<\/p>\n<p style=\"text-align: right;\">\u2022 \u0627\u0644\u0645\u0642\u0627\u0648\u0645\u06291 : 1339\u2022 \u0627\u0644\u0645\u0642\u0627\u0648\u0645\u06292 : 1344\u2022 \u0627\u0644\u0645\u0642\u0627\u0648\u0645\u06293 : 1350<\/p>\n<p style=\"text-align: right;\">\u0627\u0644\u0646\u0642\u0637\u0629 \u0627\u0644\u0645\u062d\u0648\u0631\u064a\u0629 : 1332<\/p>\n<p style=\"text-align: right;\">\u2022 \u0627\u0644\u062f\u0639\u0645 1 : 1325\u2022 \u0627\u0644\u062f\u0639\u0645 2 : 1320\u2022 \u0627\u0644\u062f\u0639\u0645 3 : 1315<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062a\u062f\u0627\u0648\u0644 \u0645\u0639\u062f\u0646 \u0627\u0644\u0630\u0647\u0628 \u0641\u064a \u062d\u062f\u0648\u062f 90 \u0646\u0642\u0637\u0629 \u0645\u0639 \u0625\u062a\u062c\u0627\u0647 \u0639\u0627\u0645 \u0647\u0627\u0628\u0637 \u062d\u064a\u062b \u0625\u0641\u062a\u062a\u062d \u0639\u0646\u062f 1326.27 \u0648 \u0623\u063a\u0644\u0642 \u0639\u0646\u062f 1326.23 \u0648 \u0648\u0635\u0644 \u0644\u0623\u0639\u0644\u064a \u0633\u0639\u0631 \u0639\u0646\u062f 1333.32 \u0643\u0627\u0646 \u0623\u062f\u0646\u064a \u0633\u0639\u0631 \u0644\u0644\u0630\u0647\u0628 \u0639\u0646\u062f 1325.44 \u0646\u062c\u062d \u0627\u0644\u0645\u0639\u062f\u0646 \u0641\u064a \u062a\u062d\u0642\u064a\u0642 \u0645\u0633\u062a\u0647\u062f\u0641\u0647 \u0627\u0644\u0623\u0648\u0644 \u0639\u0646\u062f 1332 . \u0648 \u062a\u062f\u0627\u0648\u0644 \u0627\u0644\u0645\u0639\u062f\u0646 \u0627\u0644\u064a\u0648\u0645 \u0628\u0633\u0644\u0628\u064a\u0629 \u0627\u0633\u0641\u0644 \u0646\u0642\u0637\u062a\u0629 \u0627\u0644\u0645\u062d\u0648\u0631\u064a\u0629 1332, \u0648\u062a\u062f\u0627\u0648\u0644 \u0627\u0644\u0632\u0648\u062c \u0627\u0633\u0641\u0644 \u0627\u0644\u0645\u062a\u0648\u0633\u0637\u0627\u062a \u0627\u0644\u0633\u0639\u0631\u064a\u0629 20 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":13822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[274],"tags":[279,308,276,297],"class_list":["post-16088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-274","tag-279","tag-308","tag-276","tag-297"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Windsor Brokers Blog | Forex Market Analysis &amp; Trading Insights<\/title>\n<meta name=\"description\" content=\"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Windsor Brokers Blog | Forex Market Analysis &amp; Trading Insights\" \/>\n<meta property=\"og:description\" content=\"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/\" \/>\n<meta property=\"og:site_name\" content=\"Windsor Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/windsorbrokers\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-06T06:57:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/gold-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"312\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Constantinos Hadjipetrou\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@windsorbrokers\" \/>\n<meta name=\"twitter:site\" content=\"@windsorbrokers\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"Constantinos Hadjipetrou\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/\"},\"author\":{\"name\":\"Constantinos Hadjipetrou\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/person\\\/49da2144a6c5f4fca53736e8dc7ec80d\"},\"headline\":\"\u0627\u0644\u0630\u0647\u0628 \u064a\u062a\u0639\u0631\u0636 \u0644\u0645\u0648\u062c\u0629 \u0628\u064a\u0639 \u0642\u0648\u064a\u0629 \u0648\u0633\u0637 \u062a\u0631\u0627\u062c\u0639 \u0627\u0644\u0637\u0644\u0628 \u0639\u0644\u0649 \u0627\u0644\u0645\u0644\u0627\u0630\u0627\u062a \u0627\u0644\u0627\u0645\u0646\u0629 \u0628\u0639\u062f \u0627\u0646\u062d\u0633\u0627\u0631 \u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629\",\"datePublished\":\"2018-04-06T06:57:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/gold-1.png\",\"keywords\":[\"\u062a\u062d\u0644\u064a\u0644_\u0641\u0646\u064a\",\"\u0630\u0647\u0628\",\"\u0641\u0648\u0631\u0643\u0633\",\"\u0648\u0646\u062f\u0633\u0648\u0631_\u0628\u0631\u0648\u0643\u0631\u0632\"],\"articleSection\":[\"\u0627\u0644\u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u064a\u0648\u0645\u064a\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/\",\"name\":\"Windsor Brokers Blog | Forex Market Analysis & Trading Insights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/gold-1.png\",\"datePublished\":\"2018-04-06T06:57:29+00:00\",\"description\":\"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/gold-1.png\",\"contentUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/gold-1.png\",\"width\":600,\"height\":312},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0630\u0647\u0628 \u064a\u062a\u0639\u0631\u0636 \u0644\u0645\u0648\u062c\u0629 \u0628\u064a\u0639 \u0642\u0648\u064a\u0629 \u0648\u0633\u0637 \u062a\u0631\u0627\u062c\u0639 \u0627\u0644\u0637\u0644\u0628 \u0639\u0644\u0649 \u0627\u0644\u0645\u0644\u0627\u0630\u0627\u062a \u0627\u0644\u0627\u0645\u0646\u0629 \u0628\u0639\u062f \u0627\u0646\u062d\u0633\u0627\u0631 \u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/\",\"name\":\"Windsor Brokers Blog\",\"description\":\"Forex &amp; CFD Market Analysis\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#organization\",\"name\":\"Windsor Brokers\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Windsor-Brokers.png\",\"contentUrl\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Windsor-Brokers.png\",\"width\":600,\"height\":350,\"caption\":\"Windsor Brokers\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/windsorbrokers\",\"https:\\\/\\\/x.com\\\/windsorbrokers\",\"https:\\\/\\\/www.instagram.com\\\/windsorbrokerscom\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/windsorbrokersforex\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/windsor-brokers\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/#\\\/schema\\\/person\\\/49da2144a6c5f4fca53736e8dc7ec80d\",\"name\":\"Constantinos Hadjipetrou\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91302c66a33d652546dccdd587855c25a46132dc57ec8fa5941d848a30479256?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91302c66a33d652546dccdd587855c25a46132dc57ec8fa5941d848a30479256?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/91302c66a33d652546dccdd587855c25a46132dc57ec8fa5941d848a30479256?s=96&d=mm&r=g\",\"caption\":\"Constantinos Hadjipetrou\"},\"url\":\"https:\\\/\\\/blog.windsorbrokers.com\\\/ar\\\/author\\\/constantinos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Windsor Brokers Blog | Forex Market Analysis & Trading Insights","description":"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"\/","og_locale":"ar_AR","og_type":"article","og_title":"Windsor Brokers Blog | Forex Market Analysis & Trading Insights","og_description":"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.","og_url":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/","og_site_name":"Windsor Blog","article_publisher":"https:\/\/www.facebook.com\/windsorbrokers","article_published_time":"2018-04-06T06:57:29+00:00","og_image":[{"width":600,"height":312,"url":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/gold-1.png","type":"image\/png"}],"author":"Constantinos Hadjipetrou","twitter_card":"summary_large_image","twitter_creator":"@windsorbrokers","twitter_site":"@windsorbrokers","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"Constantinos Hadjipetrou"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/#article","isPartOf":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/"},"author":{"name":"Constantinos Hadjipetrou","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/person\/49da2144a6c5f4fca53736e8dc7ec80d"},"headline":"\u0627\u0644\u0630\u0647\u0628 \u064a\u062a\u0639\u0631\u0636 \u0644\u0645\u0648\u062c\u0629 \u0628\u064a\u0639 \u0642\u0648\u064a\u0629 \u0648\u0633\u0637 \u062a\u0631\u0627\u062c\u0639 \u0627\u0644\u0637\u0644\u0628 \u0639\u0644\u0649 \u0627\u0644\u0645\u0644\u0627\u0630\u0627\u062a \u0627\u0644\u0627\u0645\u0646\u0629 \u0628\u0639\u062f \u0627\u0646\u062d\u0633\u0627\u0631 \u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629","datePublished":"2018-04-06T06:57:29+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/"},"wordCount":0,"publisher":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#organization"},"image":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/gold-1.png","keywords":["\u062a\u062d\u0644\u064a\u0644_\u0641\u0646\u064a","\u0630\u0647\u0628","\u0641\u0648\u0631\u0643\u0633","\u0648\u0646\u062f\u0633\u0648\u0631_\u0628\u0631\u0648\u0643\u0631\u0632"],"articleSection":["\u0627\u0644\u062a\u0642\u0631\u064a\u0631 \u0627\u0644\u064a\u0648\u0645\u064a"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/","url":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/","name":"Windsor Brokers Blog | Forex Market Analysis & Trading Insights","isPartOf":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/#primaryimage"},"image":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/gold-1.png","datePublished":"2018-04-06T06:57:29+00:00","description":"Read the latest market news, access different types of analysis, trading strategies, and financial insights from the Windsor Brokers research team.","breadcrumb":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/#primaryimage","url":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/gold-1.png","contentUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2018\/02\/gold-1.png","width":600,"height":312},{"@type":"BreadcrumbList","@id":"https:\/\/blog.windsorbrokers.com\/ar\/%d8%a7%d9%84%d8%b0%d9%87%d8%a8-%d9%8a%d8%aa%d8%b9%d8%b1%d8%b6-%d9%84%d9%85%d9%88%d8%ac%d8%a9-%d8%a8%d9%8a%d8%b9-%d9%82%d9%88%d9%8a%d8%a9-%d9%88%d8%b3%d8%b7-%d8%aa%d8%b1%d8%a7%d8%ac%d8%b9-%d8%a7%d9%84\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.windsorbrokers.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0630\u0647\u0628 \u064a\u062a\u0639\u0631\u0636 \u0644\u0645\u0648\u062c\u0629 \u0628\u064a\u0639 \u0642\u0648\u064a\u0629 \u0648\u0633\u0637 \u062a\u0631\u0627\u062c\u0639 \u0627\u0644\u0637\u0644\u0628 \u0639\u0644\u0649 \u0627\u0644\u0645\u0644\u0627\u0630\u0627\u062a \u0627\u0644\u0627\u0645\u0646\u0629 \u0628\u0639\u062f \u0627\u0646\u062d\u0633\u0627\u0631 \u0627\u0644\u062a\u0648\u062a\u0631\u0627\u062a \u0627\u0644\u062a\u062c\u0627\u0631\u064a\u0629"}]},{"@type":"WebSite","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#website","url":"https:\/\/blog.windsorbrokers.com\/ar\/","name":"Windsor Brokers Blog","description":"Forex &amp; CFD Market Analysis","publisher":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.windsorbrokers.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#organization","name":"Windsor Brokers","url":"https:\/\/blog.windsorbrokers.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2023\/05\/Windsor-Brokers.png","contentUrl":"https:\/\/blog.windsorbrokers.com\/wp-content\/uploads\/2023\/05\/Windsor-Brokers.png","width":600,"height":350,"caption":"Windsor Brokers"},"image":{"@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/windsorbrokers","https:\/\/x.com\/windsorbrokers","https:\/\/www.instagram.com\/windsorbrokerscom\/","https:\/\/www.youtube.com\/user\/windsorbrokersforex","https:\/\/www.linkedin.com\/company\/windsor-brokers\/"]},{"@type":"Person","@id":"https:\/\/blog.windsorbrokers.com\/ar\/#\/schema\/person\/49da2144a6c5f4fca53736e8dc7ec80d","name":"Constantinos Hadjipetrou","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/91302c66a33d652546dccdd587855c25a46132dc57ec8fa5941d848a30479256?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/91302c66a33d652546dccdd587855c25a46132dc57ec8fa5941d848a30479256?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/91302c66a33d652546dccdd587855c25a46132dc57ec8fa5941d848a30479256?s=96&d=mm&r=g","caption":"Constantinos Hadjipetrou"},"url":"https:\/\/blog.windsorbrokers.com\/ar\/author\/constantinos\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts\/16088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/comments?post=16088"}],"version-history":[{"count":1,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts\/16088\/revisions"}],"predecessor-version":[{"id":16090,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/posts\/16088\/revisions\/16090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/media\/13822"}],"wp:attachment":[{"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/media?parent=16088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/categories?post=16088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.windsorbrokers.com\/ar\/wp-json\/wp\/v2\/tags?post=16088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}